{"id":25035,"date":"2026-03-27T11:14:22","date_gmt":"2026-03-27T16:14:22","guid":{"rendered":"https:\/\/communicare.uanl.mx\/?p=25035"},"modified":"2026-03-27T11:14:22","modified_gmt":"2026-03-27T16:14:22","slug":"rector-santos-guzman-recibe-la-medalla-al-merito-civico-moises-saenz-garza","status":"publish","type":"post","link":"https:\/\/communicare.uanl.mx\/index.php\/2026\/03\/27\/rector-santos-guzman-recibe-la-medalla-al-merito-civico-moises-saenz-garza\/","title":{"rendered":"Rector Santos Guzm\u00e1n recibe la Medalla al M\u00e9rito C\u00edvico Mois\u00e9s S\u00e1enz Garza"},"content":{"rendered":"\n<p class=\"has-small-font-size\">Por: Hannia Gonz\u00e1lez-communcare.uanl.mx<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-4f03ce9aca0ec478b9456ff343dc8878\">El cabildo del municipio de Apodaca entreg\u00f3 la Medalla al M\u00e9rito C\u00edvico Mois\u00e9s S\u00e1enz Garza al Dr. med. Santos Guzm\u00e1n L\u00f3pez durante la Cuarta Sesi\u00f3n Solemne de la administraci\u00f3n. El evento se realiz\u00f3 el 22 de marzo en el marco del aniversario n\u00famero 175 de la fundaci\u00f3n de la ciudad para reconocer la trayectoria acad\u00e9mica del Rector de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n. El galard\u00f3n represent\u00f3 la distinci\u00f3n m\u00e1xima de la ciudad para los ciudadanos con impacto en el desarrollo educativo de la regi\u00f3n metropolitana. Autoridades municipales y representantes de la zona militar participaron en la ceremonia oficial en el ayuntamiento para honrar el legado del maestro Mois\u00e9s S\u00e1enz Garza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"http:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-1024x640.jpg\" alt=\"\" class=\"wp-image-25039\" style=\"width:672px;height:auto\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-1024x640.jpg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-300x188.jpg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-768x480.jpg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-1536x960.jpg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-320x200.jpg 320w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-500x313.jpg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-1000x625.jpg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n-800x500.jpg 800w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/657550921_122263659860104769_8087119076024144015_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-f59a5f2acb2aaf0a2067cbc9ba68676a\">El Rector de la UANL expres\u00f3 en sus redes sociales: \u201cMe siento profundamente honrado de haber recibido anoche la Medalla al M\u00e9rito C\u00edvico Mois\u00e9s S\u00e1enz Garza por parte del municipio de Apodaca, un reconocimiento que, m\u00e1s que a mi persona, es una distinci\u00f3n al esfuerzo y la labor realizada por toda la gran comunidad universitaria de la UANL, la cual nos ha permitido destacar a nivel regional, nacional e internacional como una instituci\u00f3n de excelencia\u201d. La autoridad universitaria afirm\u00f3 que el trabajo colectivo fortalece la vinculaci\u00f3n con todos los sectores de la sociedad civil durante su mensaje de agradecimiento. El l\u00edder de la m\u00e1xima casa de estudios tambi\u00e9n reconoci\u00f3 el esfuerzo de las familias por alcanzar la superaci\u00f3n personal mediante los programas de estudio actuales.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25038\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1024x683.jpeg\" alt=\"\" class=\"wp-image-25038\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-800x533.jpeg 800w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"631\" data-id=\"25037\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-1024x631.jpeg\" alt=\"\" class=\"wp-image-25037\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-1024x631.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-300x185.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-768x473.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-1536x946.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-500x308.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-1000x616.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1-800x493.jpeg 800w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-10.30.12-AM-1.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-6294b61bc0045bc2eb6fa2b46839fe3d\">El Alcalde C\u00e9sar Garza Arredondo resalt\u00f3 la trayectoria del homenajeado como un ejemplo de superaci\u00f3n para los j\u00f3venes de la localidad durante su intervenci\u00f3n en la premiaci\u00f3n. El Presidente Municipal subray\u00f3 la capacidad de la ense\u00f1anza para transformar la vida de las personas con deseos de crecimiento profesional en el norte del pa\u00eds, reconociendo la apertura del Dr. med. Santos Guzm\u00e1n L\u00f3pez para colaborar en proyectos de salud mental y en el fortalecimiento de los servicios odontol\u00f3gicos para la poblaci\u00f3n vulnerable.&nbsp;El evento concluy\u00f3 con el compromiso de las instituciones de continuar el trabajo en beneficio del desarrollo humano de la regi\u00f3n y la formaci\u00f3n de ciudadanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Hannia Gonz\u00e1lez-communcare.uanl.mx El cabildo del municipio de Apodaca entreg\u00f3 la Medalla al M\u00e9rito C\u00edvico Mois\u00e9s S\u00e1enz Garza al Dr. med. Santos Guzm\u00e1n L\u00f3pez durante la Cuarta Sesi\u00f3n Solemne de la administraci\u00f3n. El evento se realiz\u00f3 el 22 de marzo en el marco del aniversario n\u00famero 175 de la fundaci\u00f3n de la ciudad para reconocer <a class=\"article-read-more\" href=\"https:\/\/communicare.uanl.mx\/index.php\/2026\/03\/27\/rector-santos-guzman-recibe-la-medalla-al-merito-civico-moises-saenz-garza\/\">&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":25040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-25035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notiuanl"],"_links":{"self":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25035"}],"version-history":[{"count":2,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25035\/revisions"}],"predecessor-version":[{"id":25048,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25035\/revisions\/25048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/media\/25040"}],"wp:attachment":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}