{"id":25244,"date":"2026-05-07T11:09:41","date_gmt":"2026-05-07T16:09:41","guid":{"rendered":"https:\/\/communicare.uanl.mx\/?p=25244"},"modified":"2026-05-07T11:11:37","modified_gmt":"2026-05-07T16:11:37","slug":"mercado-mederos-impulsa-el-talento-emprendedor-estudiantil-en-la-uanl","status":"publish","type":"post","link":"https:\/\/communicare.uanl.mx\/index.php\/2026\/05\/07\/mercado-mederos-impulsa-el-talento-emprendedor-estudiantil-en-la-uanl\/","title":{"rendered":"Mercado Mederos impulsa el talento emprendedor estudiantil en la UANL"},"content":{"rendered":"\n<p class=\"has-small-font-size\">Por: Camila Polanco-communicare.uanl.mx || Fotograf\u00eda: Denisse Cespedes -communicare.uanl.mx <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-301403185b1db5a5cddc1b8261e77e0b\">Con el objetivo de brindar un espacio para que las y los estudiantes compartieran sus proyectos y fortalecieran sus ideas de negocio, el pasado 29 de Abril la Facultad de Ciencias de la Comunicaci\u00f3n llev\u00f3 a cabo el Mercado Mederos 2026, evento que reuni\u00f3 a emprendedores universitarios en un ambiente lleno de creatividad, convivencia y apoyo al comercio local estudiantil.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25283\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-1024x683.jpeg\" alt=\"\" class=\"wp-image-25283\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5516-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25282\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-1024x683.jpeg\" alt=\"\" class=\"wp-image-25282\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5515-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25275\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-1024x683.jpeg\" alt=\"\" class=\"wp-image-25275\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5466-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-ec67343bf29b02a9f269ba571db343e1\">Durante la jornada, alumnos de distintas facultades del Campus Mederos instalaron sus m\u00f3dulos para ofrecer una gran variedad de productos. Entre los art\u00edculos disponibles se pudieron encontrar comida, snacks, postres, joyer\u00eda, ropa y otros productos originales que captaron la atenci\u00f3n de los asistentes.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-532189ab244b3be910b167a460045b7f\">El evento se convirti\u00f3 en una oportunidad para que la comunidad estudiantil conozca propuestas innovadoras y respalde el esfuerzo de sus compa\u00f1eros, quienes aprovecharon el espacio para promocionar sus marcas, interactuar y dar a conocer sus emprendimientos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25280\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-1024x683.jpeg\" alt=\"\" class=\"wp-image-25280\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5502-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25277\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-1024x683.jpeg\" alt=\"\" class=\"wp-image-25277\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5481-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25276\" src=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-1024x683.jpeg\" alt=\"\" class=\"wp-image-25276\" srcset=\"https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-1024x683.jpeg 1024w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-300x200.jpeg 300w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-768x512.jpeg 768w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-1536x1024.jpeg 1536w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-2048x1365.jpeg 2048w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-1200x800.jpeg 1200w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-500x333.jpeg 500w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-1000x667.jpeg 1000w, https:\/\/communicare.uanl.mx\/wp-content\/uploads\/2026\/05\/IMG_5473-800x533.jpeg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-8b9238e653d894b17f8e1ae826e26696\">Adem\u00e1s de la actividad comercial, el ambiente estuvo acompa\u00f1ado de m\u00fasica y entretenimiento gracias a la participaci\u00f3n de los grupos Amys, Marca Plena, Freestyle y Dj Club, quienes aportaron energ\u00eda y dinamismo al evento con distintas presentaciones para el p\u00fablico presente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Camila Polanco-communicare.uanl.mx || Fotograf\u00eda: Denisse Cespedes -communicare.uanl.mx Con el objetivo de brindar un espacio para que las y los estudiantes compartieran sus proyectos y fortalecieran sus ideas de negocio, el pasado 29 de Abril la Facultad de Ciencias de la Comunicaci\u00f3n llev\u00f3 a cabo el Mercado Mederos 2026, evento que reuni\u00f3 a emprendedores universitarios <a class=\"article-read-more\" href=\"https:\/\/communicare.uanl.mx\/index.php\/2026\/05\/07\/mercado-mederos-impulsa-el-talento-emprendedor-estudiantil-en-la-uanl\/\">&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":25281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-25244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notifcc"],"_links":{"self":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25244"}],"version-history":[{"count":5,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25244\/revisions"}],"predecessor-version":[{"id":25284,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/posts\/25244\/revisions\/25284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/media\/25281"}],"wp:attachment":[{"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/communicare.uanl.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}